{"id":496,"date":"2025-06-18T13:35:57","date_gmt":"2025-06-18T13:35:57","guid":{"rendered":"https:\/\/familiasmadridnorte.es\/?page_id=496"},"modified":"2025-06-18T13:45:46","modified_gmt":"2025-06-18T13:45:46","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/familiasmadridnorte.es\/en\/aviso-legal\/","title":{"rendered":"Legal Notice"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"496\" class=\"elementor elementor-496\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b056b2 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"0b056b2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b8acdea animated-slow elementor-invisible\" data-id=\"b8acdea\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb2f181 elementor-widget elementor-widget-heading\" data-id=\"bb2f181\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Legal Notice<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-ab584ea e-flex e-con-boxed e-con e-parent\" data-id=\"ab584ea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0a36a7 elementor-widget elementor-widget-text-editor\" data-id=\"f0a36a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><u>Aviso Legal e informaci\u00f3n sobre las condiciones de uso del sitio web<\/u><\/strong><\/p><p>En cumplimiento con el deber de informaci\u00f3n estipulado en art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico,\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>, en calidad de titular del sitio web\u00a0\u00a0<strong>WWW.FAMILIASMADRIDNORTE.ES<\/strong><strong>\u00a0<\/strong>hace constar:<\/p><p><strong><u>1- Datos identificativos:<\/u><\/strong><\/p><ul><li><ul><li>Denominaci\u00f3n social: ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/li><li>CIF: G83779702<\/li><li>Domicilio social: PASEO GUADALAJARA 5, DESPACHO 1 28702 SAN SEBASTIAN DE LOS REYES MADRID<\/li><li>Correo electr\u00f3nico: INFO@FAMILIASMADRIDNORTE.ES<\/li><li>Datos de inscripci\u00f3n en el Registro Mercantil:<br \/><br \/>La presente informaci\u00f3n conforma y regula las condiciones de uso, las limitaciones de responsabilidad y las obligaciones que, los usuarios de la p\u00e1gina Web que se publica bajo el nombre de dominio\u00a0<strong>WWW.FAMILIASMADRIDNORTE.ES<\/strong>\u00a0asumen y se comprometen a respetar. En cualquier caso, la aceptaci\u00f3n del aviso legal no supone el establecimiento de relaci\u00f3n contractual entre USUARIO y el RESPONSABLE del sitio Web, ni afectar\u00e1 a aquella que tuvieran previamente. En lo referente al buen uso del sitio Web, toda la informaci\u00f3n contenida, se estar\u00e1 a los derechos, deberes y obligaciones que la legislaci\u00f3n vigente establezca en cada momento, as\u00ed como las establecidas en el presente aviso legal.<\/li><\/ul><\/li><\/ul><p><strong><u>2- Definiciones<\/u><\/strong><\/p><ul><li><ul><li>\u201cP\u00e1gina\u201d, dominio\u00a0<strong>FAMILIASMADRIDNORTE.ES<\/strong>, que se pone a<br \/>disposici\u00f3n de los Usuarios de Internet.<br \/><br \/><\/li><li>\u201cUsuario\u201d, persona f\u00edsica o jur\u00eddica que utiliza o navega por la P\u00e1gina.<br \/><br \/><\/li><li>\u201cContenido\u201d, son las p\u00e1ginas que conforman la totalidad del dominio WWW.FAMILIASMADRIDNORTE.ES\u00a0<strong>,<\/strong>\u00a0las cuales conforman la informaci\u00f3n y los servicios que\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0\u00a0pone a disposici\u00f3n de los Usuarios de Internet. En ellas se contienen los mensajes, textos, fotograf\u00edas, gr\u00e1ficos, iconos, logos, tecnolog\u00eda, links, texturas, dibujos, archivos de sonido y\/o imagen, grabaciones, software, aspecto, dise\u00f1o gr\u00e1fico y c\u00f3digos fuente y, en general, cualquier clase de material contenido en la P\u00e1gina.<br \/><br \/><\/li><li>\u201cWeb\u201d, palabra t\u00e9cnica que describe el sistema de acceso a la informaci\u00f3n v\u00eda Internet, que se configura por medio de p\u00e1ginas confeccionadas con lenguaje HTML o similar, y mecanismos de programaci\u00f3n tales como java, javascript, PHP, u otros, etc. En estas p\u00e1ginas dise\u00f1adas y publicadas bajo un nombre de dominio Internet son el resultado de la informaci\u00f3n que el titular pone a disposici\u00f3n de los Usuarios de Internet.<br \/><br \/><\/li><li>\u201cHiperenlace\u201d, t\u00e9cnica por la cual un Usuario puede navegar por diferentes p\u00e1ginas de la Web, o por Internet, con un simple click sobre el texto, icono, bot\u00f3n o indicativo que contiene el enlace.<br \/><br \/><\/li><li>\u201cCookies\u201d, medio t\u00e9cnico para la \u201ctrazabilidad\u201d y seguimiento de la navegaci\u00f3n en los sitios Web. Son peque\u00f1os ficheros de texto que se escriben en el ordenador del Usuario. Este m\u00e9todo tiene implicaciones sobre la privacidad, por lo que\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID\u00a0<\/strong>\u00a0\u00a0avisar\u00e1 oportuna y fehacientemente de su utilizaci\u00f3n en el momento en que se implanten en la P\u00e1gina.<\/li><\/ul><\/li><\/ul><p><strong><u>3- Usuarios \/ Condiciones de uso<\/u><\/strong><\/p><p>El acceso y\/o uso de este sitio web de\u00a0<strong>WWW.FAMILIASMADRIDNORTE.ES<\/strong>\u00a0atribuye la condici\u00f3n de USUARIO, que acepta, desde dicho acceso y\/o uso, los presentes t\u00e9rminos de uso, sin reservas de todas y cada una de las cl\u00e1usulas y condiciones generales incluidas en el Aviso Legal.<\/p><p>Si el Usuario no estuviera conforme con las cl\u00e1usulas y condiciones de uso de este Aviso Legal, se abstendr\u00e1 de utilizar la P\u00e1gina.<\/p><p>\u00a0<\/p><p><strong><u>4- Uso del sitio web<\/u><\/strong><\/p><p><strong>WWW.FAMILIASMADRIDNORTE.ES<\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0proporciona el acceso a art\u00edculos, informaciones y datos (en adelante, \u201cLOS CONTENIDOS\u201d) propiedad de\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID\u00a0<\/strong>\u00a0\u00a0\u00a0. El USUARIO asume la responsabilidad del uso de la web.<\/p><p>Algunas p\u00e1ginas del sitio Web (<strong>WWW.FAMILIASMADRIDNORTE.ES<\/strong>) pueden permitir la participaci\u00f3n mediante comentarios, pudiendo en tal caso cualquier usuario enviar textos a trav\u00e9s del formulario establecido a tal efecto. Al enviar dichos textos, haciendo clic en el enlace correspondiente, El USUARIO se compromete y acepta, a hacer un uso adecuado de los contenidos que \u00a0<strong>WWW.FAMILIASMADRIDNORTE.ES<\/strong>\u00a0\u00a0 \u00a0\u00a0ofrece a trav\u00e9s de su web, a no emplearlos para:<\/p><ol><li><ol><li>incurrir en actividades il\u00edcitas, ilegales o contrarias a la buena fe y al orden p\u00fablico.<br \/><br \/><\/li><li>difundir contenidos o propaganda de car\u00e1cter racista, xen\u00f3fobo, pornogr\u00e1fico-ilegal, de apolog\u00eda del terrorismo o atentatorio contra los derechos humanos.<br \/><br \/><\/li><li>provocar da\u00f1os en los sistemas f\u00edsicos y l\u00f3gicos de (<strong>FAMILIASMADRIDNORTE.ES<\/strong>), de sus proveedores o de terceras personas, introducir o difundir en la red virus inform\u00e1ticos o cualesquiera otros sistemas f\u00edsicos o l\u00f3gicos que sean susceptibles de provocar los da\u00f1os anteriormente mencionados.<br \/><br \/><\/li><li>intentar acceder y, en su caso, utilizar las cuentas de correo electr\u00f3nico de otros usuarios y modificar o manipular sus mensajes.<br \/><br \/><\/li><li>En definitiva, a respetar la legislaci\u00f3n aplicable, la moral y buenas costumbres generalmente aceptadas, el orden p\u00fablico y las presentes condiciones generales de acceso y utilizaci\u00f3n.<\/li><\/ol><\/li><\/ol><p>A tal efecto, EL USUARIO se obliga y compromete a NO utilizar cualquiera de los Contenidos con fines o efectos il\u00edcitos, prohibidos en el Aviso Legal o por la legislaci\u00f3n vigente, lesivos de los derechos e intereses de terceros, o que de cualquier forma puedan da\u00f1ar, inutilizar, sobrecargar, deteriorar o impedir la normal utilizaci\u00f3n de los Contenidos, los equipos inform\u00e1ticos o los documentos, archivos y toda clase de contenidos almacenados en cualquier equipo inform\u00e1tico propios o contratados por\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>, de otros Usuarios o de cualquier usuario de Internet (hardware y software).<\/p><p>EL USUARIO se obliga y se compromete a no transmitir, difundir o poner a disposici\u00f3n de terceros cualquier clase de material contenido en la P\u00e1gina, tales como informaciones, textos, datos, contenidos, mensajes, gr\u00e1ficos, dibujos, archivos de sonido y\/o imagen, fotograf\u00edas, grabaciones, software, logotipos, marcas, iconos, tecnolog\u00eda, fotograf\u00edas, software, enlaces, dise\u00f1o gr\u00e1fico y c\u00f3digos fuente, o cualquier otro material al que tuviera acceso en su condici\u00f3n de Usuario de la P\u00e1gina, sin que esta enumeraci\u00f3n tenga car\u00e1cter limitativo.<\/p><p>Asimismo, de conformidad con todo ello, EL USUARIO no podr\u00e1:<\/p><ul><li><ul><li>Reproducir, copiar, distribuir, poner a disposici\u00f3n o de cualquier otra forma comunicar p\u00fablicamente, transformar o modificar los Contenidos, a menos que se cuente con la autorizaci\u00f3n escrita y expl\u00edcita de\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID\u00a0<\/strong>, que es titular de los correspondientes derechos, o bien que ello resulte legalmente permitido.<br \/><br \/><\/li><li>Suprimir, manipular o de cualquier forma alterar el \u00abcopyright\u00bb y dem\u00e1s datos identificativos de la reserva de derechos de\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0o de sus titulares, de las huellas y\/o identificadores digitales, o de cualesquiera otros medios t\u00e9cnicos establecidos para su reconocimiento.<br \/><br \/><\/li><li>El Usuario deber\u00e1 abstenerse de obtener e incluso de intentar obtener los Contenidos empleando para ello medios o procedimientos distintos de los que, seg\u00fan los casos, se hayan puesto a su disposici\u00f3n a este efecto o se hayan indicado a este efecto en las p\u00e1ginas Web donde se encuentren los Contenidos o, en general, de los que se empleen habitualmente en Internet a este efecto siempre que no entra\u00f1en un riesgo de da\u00f1o o inutilizaci\u00f3n de la P\u00e1gina, y\/o de los Contenidos.<\/li><\/ul><\/li><\/ul><p><strong><u>5- Pol\u00edtica de privacidad. Protecci\u00f3n de Datos<\/u><\/strong><\/p><p><strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0es consciente de la importancia de la protecci\u00f3n de datos, as\u00ed como de la privacidad de EL USUARIO y por ello, ha implementado una pol\u00edtica de tratamiento de datos orientada a proveer la m\u00e1xima seguridad en el uso y recogida de los mismos, garantizando el cumplimiento de la normativa vigente en la materia y configurando dicha pol\u00edtica como uno de los pilares b\u00e1sicos en las l\u00edneas de actuaci\u00f3n de la entidad. Por ello,\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>, insiste en la lectura obligada de su\u00a0<u>Pol\u00edtica de Privacidad:\u00a0<\/u><strong>WWW.FAMILIASMADRIDNORTE.ES<\/strong>\u00a0<\/p><p><strong><u>6- Hiperenlaces<\/u><\/strong><\/p><p>Como un servicio a nuestros visitantes, nuestro sitio web puede incluir hiperv\u00ednculos a otros sitios que no son operados o controlados por\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID\u00a0<\/strong>\u00a0\u00a0\u00a0. Por ello,\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>, \u00a0no garantiza, ni se hace responsable de la licitud, fiabilidad, utilidad, veracidad y actualidad de los contenidos de tales sitios web o de sus pr\u00e1cticas de privacidad. Por favor, antes de proporcionar su informaci\u00f3n personal a estos sitios web ajenos a\u00a0<strong>WWW.FAMILIASMADRIDNORTE.ES<br \/><\/strong>\u00a0tenga en cuenta que sus pr\u00e1cticas de privacidad pueden diferir de las nuestras.<\/p><p>Asimismo, aquellas personas que se propongan establecer hiperenlaces entre su p\u00e1gina Web y la nuestra (<strong>WWW.FAMILIASMADRIDNORTE.ES<\/strong>) deber\u00e1n observar y cumplir las condiciones siguientes:<\/p><ul><li><ul><li>No ser\u00e1 necesaria autorizaci\u00f3n previa cuando el Hiperenlace permita \u00fanicamente el acceso a la p\u00e1gina de inicio, pero no podr\u00e1 reproducirla de ninguna forma. Cualquier otra forma de Hiperenlace requerir\u00e1 la autorizaci\u00f3n expresa e inequ\u00edvoca por escrito por parte de\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID.<\/strong><br \/><br \/><\/li><li>No se crear\u00e1n \u201cmarcos\u201d (\u201c<em>frames<\/em>\u201d) con las p\u00e1ginas Web ni sobre las p\u00e1ginas Web de\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>.<br \/><br \/><\/li><li>No se realizar\u00e1n manifestaciones o indicaciones falsas, inexactas, u ofensivas sobre\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>sus directivos, sus empleados o colaboradores, o de las personas que se relacionen en la P\u00e1gina por cualquier motivo, o de los Usuarios de las P\u00e1gina, o de los Contenidos suministrados.<br \/><br \/><\/li><li>No se declarar\u00e1 ni se dar\u00e1 a entender que\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0ha autorizado el Hiperenlace o que ha supervisado o asumido de cualquier forma los Contenidos ofrecidos o puestos a disposici\u00f3n de la p\u00e1gina Web en la que se establece el Hiperenlace.<br \/><br \/><\/li><li>La p\u00e1gina Web en la que se establezca el Hiperenlace solo podr\u00e1 contener lo estrictamente necesario para identificar el destino del Hiperenlace.<br \/><br \/><\/li><li>La p\u00e1gina Web en la que se establezca el Hiperenlace no contendr\u00e1 informaciones o contenidos il\u00edcitos, contrarios a la moral y a las buenas costumbres generalmente aceptadas y al orden p\u00fablico, as\u00ed como tampoco contendr\u00e1 contenidos contrarios a cualesquiera derechos de terceros<\/li><\/ul><\/li><\/ul><p><strong><u>7- Modificaci\u00f3n del Aviso Legal<\/u><\/strong><\/p><p>Con el fin de mejorar las prestaciones del sitio Web,\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0\u00a0 \u00a0se reserva la facultad de efectuar, en cualquier momento y sin necesidad de previo aviso, modificaciones y actualizaciones de la informaci\u00f3n contenida en el sitio Web, de la configuraci\u00f3n y dise\u00f1o de \u00e9ste y del presente aviso legal, as\u00ed como de cualesquiera otras condiciones particulares. Cuando dichas condiciones particulares afecten al USUARIO, ser\u00e1 debidamente informado, pudiendo abstenerse de la aceptaci\u00f3n y aplic\u00e1ndose aquellas condiciones vigentes hasta el momento y hasta finalizar la relaci\u00f3n contractual con el propietario del sitio Web. La aceptaci\u00f3n del Aviso Legal no conlleva el establecimiento de ninguna relaci\u00f3n comercial, salvo los derechos, deberes y obligaciones que deriven del buen uso del presente sitio Web conforme a la legislaci\u00f3n vigente. Todas las actualizaciones y\/o modificaciones se comunicar\u00e1n cuando se acceda al sitio Web para que cualquier USUARIO pueda conocer el alcance de las mismas.<\/p><p><strong><u>8- Propiedad intelectual \/ industrial<\/u><\/strong><\/p><p><strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0\u00a0 \u00a0es titular de todos los derechos de propiedad intelectual e industrial de su p\u00e1gina web, as\u00ed como de los elementos contenidos en la misma (a t\u00edtulo enunciativo, im\u00e1genes, sonido, audio, v\u00eddeo, software o textos; marcas o logotipos, combinaciones de colores, estructura y dise\u00f1o, selecci\u00f3n de materiales usados, programas de ordenador necesarios para su funcionamiento, acceso y uso, etc.), titularidad de\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0\u00a0 o bien de sus licenciantes, estando todos los derechos reservados.<\/p><p>Cualquier uso no autorizado previamente por\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0\u00a0 , ser\u00e1 considerado un incumplimiento grave de los derechos de propiedad intelectual o industrial del autor.<\/p><p>El USUARIO se compromete a respetar los derechos de Propiedad Intelectual e Industrial titularidad de\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>. Podr\u00e1 visualizar los elementos de la web e incluso imprimirlos, copiarlos y almacenarlos en el disco duro de su ordenador o en cualquier otro soporte f\u00edsico siempre y cuando sea, \u00fanica y exclusivamente, para su uso personal y privado. El USUARIO deber\u00e1 abstenerse de suprimir, alterar, eludir o manipular cualquier dispositivo de protecci\u00f3n o sistema de seguridad que estuviera instalado en las p\u00e1ginas de\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong><\/p><p>Todas las marcas, nombres comerciales o signos distintivos de cualquier clase que aparecen en la P\u00e1gina son propiedad de\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0o, en su caso, de terceros que han autorizado su uso, sin que pueda entenderse que el uso o acceso al Portal y\/o a los Contenidos atribuya al Usuario derecho alguno sobre las citadas marcas, nombres comerciales y\/o signos distintivos, y sin que puedan entenderse cedidos al Usuario, ninguno de los derechos de explotaci\u00f3n que existen o puedan existir sobre dichos Contenidos.<\/p><p>De igual modo los Contenidos son propiedad intelectual de\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>,\u00a0\u00a0\u00a0 \u00a0o de terceros en su caso, por tanto, los derechos de Propiedad Intelectual son titularidad de\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0 \u00a0o de terceros que han autorizado su uso, a quienes corresponde el ejercicio exclusivo de los derechos de explotaci\u00f3n de los mismos en cualquier forma y, en especial, los derechos de reproducci\u00f3n, distribuci\u00f3n, comunicaci\u00f3n p\u00fablica y transformaci\u00f3n. Quedan expresamente prohibidas la reproducci\u00f3n, la distribuci\u00f3n y la comunicaci\u00f3n p\u00fablica, incluida su modalidad de puesta a disposici\u00f3n, de la totalidad o parte de los contenidos de esta p\u00e1gina web, con fines comerciales, en cualquier soporte y por cualquier medio t\u00e9cnico, sin la autorizaci\u00f3n de\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong><\/p><p>La utilizaci\u00f3n no autorizada de la informaci\u00f3n contenida en esta Web, as\u00ed como la lesi\u00f3n de los derechos de Propiedad Intelectual o Industrial de\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0\u00a0 \u00a0\u00a0o de terceros incluidos en la P\u00e1gina que hayan cedido contenidos dar\u00e1 lugar a las responsabilidades legalmente establecidas.<\/p><p><strong><u>9- Cookies<\/u><\/strong><\/p><p>Las cookies son el medio t\u00e9cnico para la \u201ctrazabilidad\u201d y seguimiento de la navegaci\u00f3n en los Sitios Web. Son peque\u00f1os ficheros de texto que se escriben en el ordenador del Usuario. Este m\u00e9todo tiene implicaciones sobre la privacidad, por lo que\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0informa de que podr\u00e1 utilizar cookies con la finalidad de elaborar estad\u00edsticas de utilizaci\u00f3n del sitio web as\u00ed como para identificar el PC del Usuario permitiendo reconocerle en sus pr\u00f3ximas visitas. En todo caso, el usuario puede configurar su navegador para no permitir el uso de cookies en sus visitas al web site.<\/p><p><strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0\u00a0 \u00a0es consciente de la importancia de la protecci\u00f3n de datos, as\u00ed como de la privacidad de EL USUARIO y por ello, insiste en la lectura de la\u00a0<u>Pol\u00edtica de Cookies\u00a0<\/u>de nuestra p\u00e1gina web\u00a0<strong>WWW.FAMILIASMADRIDNORTE.ES<\/strong>\u00a0<\/p><p><strong><u>10- Disponibilidad de la p\u00e1gina<\/u><\/strong><\/p><p><strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0\u00a0 \u00a0no garantiza la inexistencia de interrupciones o errores en el acceso a la P\u00e1gina, a sus Contenidos, ni que \u00e9ste se encuentren actualizados, aunque desarrollar\u00e1 sus mejores esfuerzos para, en su caso, evitarlos, subsanarlos o actualizarlos. Por consiguiente,\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0no se responsabiliza de los da\u00f1os o perjuicios de cualquier tipo producidos en EL USUARIO que traigan causa de fallos o desconexiones en las redes de telecomunicaciones que produzcan la suspensi\u00f3n, cancelaci\u00f3n o interrupci\u00f3n del servicio del Portal durante la prestaci\u00f3n del mismo o con car\u00e1cter previo.<\/p><p><strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0\u00a0 \u00a0excluye, con las excepciones contempladas en la legislaci\u00f3n vigente, cualquier responsabilidad por los da\u00f1os y perjuicios de toda naturaleza que puedan deberse a la falta de disponibilidad, continuidad o calidad del funcionamiento de la P\u00e1gina y de los Contenidos, al no cumplimiento de la expectativa de utilidad que los usuarios hubieren podido atribuir a la P\u00e1gina y a los Contenidos.<\/p><p>La funci\u00f3n de los Hiperenlaces que aparecen en esta Web es exclusivamente la de informar al usuario acerca de la existencia de otras Web que contienen informaci\u00f3n sobre la materia. Dichos Hiperenlaces no constituyen sugerencia ni recomendaci\u00f3n alguna.<\/p><p><strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0\u00a0 tampoco se hace responsable de los errores de seguridad que se puedan producir, ni de los da\u00f1os que puedan causarse al sistema inform\u00e1tico del usuario (hardware y software), o a los ficheros o documentos almacenados en el mismo, como consecuencia de:<\/p><ul><li><ul><li>La presencia de un virus en el ordenador del usuario que sea utilizado para la conexi\u00f3n a los servicios y contenidos del sitio Web.<br \/><br \/><\/li><li>Un mal funcionamiento del navegador o el uso de versiones no actualizadas del mismo.<\/li><\/ul><\/li><\/ul><p><strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0 \u00a0no se hace responsable de los contenidos de dichas p\u00e1ginas enlazadas, del funcionamiento o utilidad de los Hiperenlaces ni del resultado de dichos enlaces, ni garantiza la ausencia de virus u otros elementos en los mismos que puedan producir alteraciones en el sistema inform\u00e1tico (hardware y software), los documentos o los ficheros del usuario, excluyendo cualquier responsabilidad por los da\u00f1os de cualquier clase causados al usuario por este motivo.<\/p><p>El acceso a la P\u00e1gina no implica la obligaci\u00f3n por parte de\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0\u00a0 \u00a0de controlar la ausencia de virus, gusanos o cualquier otro elemento inform\u00e1tico da\u00f1ino. Corresponde al Usuario, en todo caso, la disponibilidad de herramientas adecuadas para la detecci\u00f3n y desinfecci\u00f3n de programas inform\u00e1ticos da\u00f1inos, por lo tanto,\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0no se hace responsable de los posibles errores de seguridad que se puedan producir durante la prestaci\u00f3n del servicio de la P\u00e1gina, ni de los posibles da\u00f1os que puedan causarse al sistema inform\u00e1tico del usuario o de terceros (hardware y software), los ficheros o documentos almacenados en el mismo, como consecuencia de la presencia de virus en el ordenador del usuario utilizado para la conexi\u00f3n a los servicios y contenidos de la Web, de un mal funcionamiento del navegador o del uso de versiones no actualizadas del mismo.<\/p><p><strong><u>11- Calidad de la P\u00e1gina<\/u><\/strong><\/p><p>Dado el entorno din\u00e1mico y cambiante de la informaci\u00f3n y servicios que se suministran por medio de la P\u00e1gina,\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0\u00a0 \u00a0su mejor esfuerzo, pero no garantiza la completa veracidad, exactitud, fiabilidad, utilidad y\/o actualidad de los Contenidos.<\/p><p>La informaci\u00f3n contenida en las p\u00e1ginas que componen este Portal s\u00f3lo tiene car\u00e1cter informativo, consultivo, divulgativo y publicitario. En ning\u00fan caso ofrecen ni tienen car\u00e1cter de compromiso vinculante o contractual.<\/p><p><strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0\u00a0\u00a0 excluye toda responsabilidad por las decisiones que EL USUARIO pueda tomar basado en esta informaci\u00f3n, as\u00ed como por los posibles errores tipogr\u00e1ficos que puedan contener los documentos y gr\u00e1ficos de la P\u00e1gina. La informaci\u00f3n est\u00e1 sometida a posibles cambios peri\u00f3dicos sin previo aviso de su contenido por ampliaci\u00f3n, mejora, correcci\u00f3n o actualizaci\u00f3n de los Contenidos.<\/p><p><strong><u>12- Disponibilidad de los Contenidos<\/u><\/strong><\/p><p>La prestaci\u00f3n del servicio de la P\u00e1gina y de los Contenidos tiene, en principio, duraci\u00f3n indefinida.\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>, no obstante, queda autorizada para dar por terminada o suspender la prestaci\u00f3n del servicio de la P\u00e1gina y\/o de cualquiera de los Contenidos en cualquier momento. Cuando ello sea razonablemente posible,\u00a0<strong>ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID<\/strong>\u00a0advertir\u00e1 previamente la terminaci\u00f3n o suspensi\u00f3n de la P\u00e1gina.<\/p><p><strong><u>13- Jurisdicci\u00f3n<\/u><\/strong><\/p><p>Para cuantas cuestiones se susciten sobre la interpretaci\u00f3n, aplicaci\u00f3n y cumplimiento de este Aviso Legal, as\u00ed como de las reclamaciones que puedan derivarse de su uso, todas las partes intervinientes se someten a la legislaci\u00f3n espa\u00f1ola vigente para determinar la jurisdicci\u00f3n competente en cada caso espec\u00edfico.<\/p><p><strong><u>14- Legislaci\u00f3n aplicable<\/u><\/strong><\/p><p>Las presentes condiciones se rigen por la legislaci\u00f3n espa\u00f1ola.<\/p><p>Reservados todos los derechos de autor por las leyes y tratados internacionales de propiedad intelectual. Queda expresamente prohibida su copia, reproducci\u00f3n o difusi\u00f3n, total o parcial, por cualquier medio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Aviso Legal Aviso Legal e informaci\u00f3n sobre las condiciones de uso del sitio web En cumplimiento con el deber de informaci\u00f3n estipulado en art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico,\u00a0ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID, en calidad de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-496","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aviso Legal - Familias Numerosas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/familiasmadridnorte.es\/en\/aviso-legal\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso Legal - Familias Numerosas\" \/>\n<meta property=\"og:description\" content=\"Aviso Legal Aviso Legal e informaci\u00f3n sobre las condiciones de uso del sitio web En cumplimiento con el deber de informaci\u00f3n estipulado en art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico,\u00a0ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID, en calidad de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/familiasmadridnorte.es\/en\/aviso-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Familias Numerosas\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-18T13:45:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/familiasmadridnorte.es\/wp-content\/uploads\/2025\/11\/Logo_AFAN-enlace.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/familiasmadridnorte.es\\\/aviso-legal\\\/\",\"url\":\"https:\\\/\\\/familiasmadridnorte.es\\\/aviso-legal\\\/\",\"name\":\"Aviso Legal - Familias Numerosas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/familiasmadridnorte.es\\\/#website\"},\"datePublished\":\"2025-06-18T13:35:57+00:00\",\"dateModified\":\"2025-06-18T13:45:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/familiasmadridnorte.es\\\/aviso-legal\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/familiasmadridnorte.es\\\/aviso-legal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/familiasmadridnorte.es\\\/aviso-legal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/familiasmadridnorte.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aviso Legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/familiasmadridnorte.es\\\/#website\",\"url\":\"https:\\\/\\\/familiasmadridnorte.es\\\/\",\"name\":\"Familias Numerosas\",\"description\":\"La Asociaci\u00f3n de Familias Numerosas Zona Norte de Madrid (AFAN Zona Norte Madrid) lleva 20 a\u00f1os apoyando y representando a las familias numerosas, defendiendo sus derechos y destacando su valiosa aportaci\u00f3n a la sociedad.\",\"publisher\":{\"@id\":\"https:\\\/\\\/familiasmadridnorte.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/familiasmadridnorte.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/familiasmadridnorte.es\\\/#organization\",\"name\":\"Familias Numerosas\",\"url\":\"https:\\\/\\\/familiasmadridnorte.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/familiasmadridnorte.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/familiasmadridnorte.es\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Logo_AFAN-1024x724-1.png\",\"contentUrl\":\"https:\\\/\\\/familiasmadridnorte.es\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Logo_AFAN-1024x724-1.png\",\"width\":1024,\"height\":724,\"caption\":\"Familias Numerosas\"},\"image\":{\"@id\":\"https:\\\/\\\/familiasmadridnorte.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso Legal - Familias Numerosas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/familiasmadridnorte.es\/en\/aviso-legal\/","og_locale":"en_GB","og_type":"article","og_title":"Aviso Legal - Familias Numerosas","og_description":"Aviso Legal Aviso Legal e informaci\u00f3n sobre las condiciones de uso del sitio web En cumplimiento con el deber de informaci\u00f3n estipulado en art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico,\u00a0ASOCIACION DE FAMILIAS NUMEROSAS ZONA NORTE DE MADRID, en calidad de [&hellip;]","og_url":"https:\/\/familiasmadridnorte.es\/en\/aviso-legal\/","og_site_name":"Familias Numerosas","article_modified_time":"2025-06-18T13:45:46+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/familiasmadridnorte.es\/wp-content\/uploads\/2025\/11\/Logo_AFAN-enlace.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/familiasmadridnorte.es\/aviso-legal\/","url":"https:\/\/familiasmadridnorte.es\/aviso-legal\/","name":"Aviso Legal - Familias Numerosas","isPartOf":{"@id":"https:\/\/familiasmadridnorte.es\/#website"},"datePublished":"2025-06-18T13:35:57+00:00","dateModified":"2025-06-18T13:45:46+00:00","breadcrumb":{"@id":"https:\/\/familiasmadridnorte.es\/aviso-legal\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/familiasmadridnorte.es\/aviso-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/familiasmadridnorte.es\/aviso-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/familiasmadridnorte.es\/"},{"@type":"ListItem","position":2,"name":"Aviso Legal"}]},{"@type":"WebSite","@id":"https:\/\/familiasmadridnorte.es\/#website","url":"https:\/\/familiasmadridnorte.es\/","name":"Large Families","description":"La Asociaci\u00f3n de Familias Numerosas Zona Norte de Madrid (AFAN Zona Norte Madrid) lleva 20 a\u00f1os apoyando y representando a las familias numerosas, defendiendo sus derechos y destacando su valiosa aportaci\u00f3n a la sociedad.","publisher":{"@id":"https:\/\/familiasmadridnorte.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/familiasmadridnorte.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/familiasmadridnorte.es\/#organization","name":"Large Families","url":"https:\/\/familiasmadridnorte.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/familiasmadridnorte.es\/#\/schema\/logo\/image\/","url":"https:\/\/familiasmadridnorte.es\/wp-content\/uploads\/2025\/06\/Logo_AFAN-1024x724-1.png","contentUrl":"https:\/\/familiasmadridnorte.es\/wp-content\/uploads\/2025\/06\/Logo_AFAN-1024x724-1.png","width":1024,"height":724,"caption":"Familias Numerosas"},"image":{"@id":"https:\/\/familiasmadridnorte.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/familiasmadridnorte.es\/en\/wp-json\/wp\/v2\/pages\/496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/familiasmadridnorte.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/familiasmadridnorte.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/familiasmadridnorte.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/familiasmadridnorte.es\/en\/wp-json\/wp\/v2\/comments?post=496"}],"version-history":[{"count":7,"href":"https:\/\/familiasmadridnorte.es\/en\/wp-json\/wp\/v2\/pages\/496\/revisions"}],"predecessor-version":[{"id":525,"href":"https:\/\/familiasmadridnorte.es\/en\/wp-json\/wp\/v2\/pages\/496\/revisions\/525"}],"wp:attachment":[{"href":"https:\/\/familiasmadridnorte.es\/en\/wp-json\/wp\/v2\/media?parent=496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}